{"id":55670,"date":"2026-06-29T22:12:46","date_gmt":"2026-06-30T01:12:46","guid":{"rendered":"https:\/\/seried.com.br\/index.php\/2026\/06\/29\/anime-famoso-e-trocas-de-ancelotti-pautam-repercussao-da-vitoria\/"},"modified":"2026-06-29T22:12:46","modified_gmt":"2026-06-30T01:12:46","slug":"anime-famoso-e-trocas-de-ancelotti-pautam-repercussao-da-vitoria","status":"publish","type":"post","link":"https:\/\/seried.com.br\/index.php\/2026\/06\/29\/anime-famoso-e-trocas-de-ancelotti-pautam-repercussao-da-vitoria\/","title":{"rendered":"Anime famoso e trocas de Ancelotti pautam repercuss\u00e3o da vit\u00f3ria"},"content":{"rendered":"<p><\/p>\n<div>\n<p><strong>A vit\u00f3ria sobre o Jap\u00e3o, por 2 a 1, em Houston (Estados Unidos), que classificou o Brasil \u00e0s oitavas de final da Copa do Mundo, ocupou manchetes na imprensa esportiva do exterior. <\/strong><\/p>\n<p><strong>As mudan\u00e7as feitas pelo t\u00e9cnico Carlo Ancelotti e o famoso <em>anime <\/em>(desenho animado japon\u00eas)\u00a0<em>Captain Tsubasa<\/em>, que possui tem\u00e1tica de futebol e ficou conhecido por aqui como <em>Super Campe\u00f5es<\/em>, pautaram a repercuss\u00e3o no exterior.<\/strong><\/p>\n<p>O espanhol Marca, por exemplo, comparou o atacante Gabriel Martinelli, autor do gol da vit\u00f3ria nos acr\u00e9scimos do segundo tempo, a Oliver Tsubasa, protagonista do <em>anime<\/em>. Na Espanha, o personagem era conhecido como Oliver Atom, termo utilizado pelo site.<\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/06\/29\/ancelotti-explica-estrategia-e-cogita-endrick-titular-nas-oitavas\/\">Ancelotti explica estrat\u00e9gia e cogita Endrick titular nas oitavas<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/06\/29\/joao-fonseca-estreia-em-wimbledon-com-3-a-0-sobre-bautista-agut\/\">Jo\u00e3o Fonseca estreia em Wimbledon com 3 a 0 sobre Bautista Agut<\/a><\/strong><\/p>\n<p>O Corriere dello Sport, da It\u00e1lia, estampou que \u201cainda n\u00e3o \u00e9 hora de Holly e Benji (nome pelo qual era chamado em alguns pa\u00edses da Europa)\u201d e que o camisa 22 brasileiro \u201cfez o Jap\u00e3o chorar\u201d. Enquanto Holly \u00e9 uma adapta\u00e7\u00e3o do nome Oliver, Benji \u00e9 Benji Wakabayashi, goleiro que inicia o <em>anime <\/em>como rival do protagonista para depois eles se tornarem grandes amigos.<\/p>\n<p>Na cr\u00f4nica do MaisFutebol, de Portugal, o gol do volante Kaishu Sano, que interceptou um passe errado do lateral Danilo, avan\u00e7ou e finalizou no canto do goleiro Alisson, foi retratado como \u201cretirado de um <em>anime<\/em>\u201c. O texto recordou que as equipes de Ancelotti, especialmente em confrontos eliminat\u00f3rios, mostram que \u201cnenhum jogo est\u00e1 perdido at\u00e9 o apito final\u201d.<\/p>\n<p>O New York Times, dos Estados Unidos, e a BBC, do Reino Unido, chamaram aten\u00e7\u00e3o \u00e0s mudan\u00e7as feitas pelo treinador, apontadas como decisivas. A reportagem do site norte-americano ressaltou que Ancelotti era a \u201ccabe\u00e7a mais fresca\u201d em Houston e destacou a op\u00e7\u00e3o por usar Gabriel Martinelli mais centralizado e n\u00e3o aberto na ponta esquerda, como seria o habitual. Foi por ali que o atacante marcou o gol da classifica\u00e7\u00e3o.<\/p>\n<p>J\u00e1 o relato do Ol\u00e9, da Argentina, foi cr\u00edtico em rela\u00e7\u00e3o \u00e0 atua\u00e7\u00e3o brasileira. \u201cCom camisa mais do que com o jogo. Com vergonha mais do que com as ideias. Com uma Vinidepend\u00eancia total\u201d, iniciou a cr\u00f4nica, em refer\u00eancia \u00e0 import\u00e2ncia do atacante Vin\u00edcius J\u00fanior. E brincou com uma cita\u00e7\u00e3o popular que menciona a cidade que recebeu o jogo desta segunda: \u201cHouston, o escrete estava com problemas\u201d.<\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/06\/28\/ancelotti-omite-escalacao-do-brasil-na-vespera-do-duelo-contra-o-japao\/\">Ancelotti omite escala\u00e7\u00e3o do Brasil na v\u00e9spera do duelo contra o Jap\u00e3o<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2026\/06\/28\/com-gol-no-final-canada-vence-africa-do-sul-e-vai-as-oitavas-da-copa\/\">Com gol no final, Canad\u00e1 vence Africa do Sul e vai \u00e0s oitavas da Copa<\/a><\/strong><\/p>\n<p>Tom semelhante \u00e0 an\u00e1lise do Record, do M\u00e9xico. Segundo a cr\u00f4nica, Ancelotti foi um \u201cmestre do xadrez\u201d, mas que \u201cisso, por si s\u00f3, n\u00e3o bastar\u00e1 para as pr\u00f3ximas fases\u201d.<\/p>\n<p><strong>Do lado japon\u00eas, a repercuss\u00e3o, naturalmente, foi em tom de lamenta\u00e7\u00e3o. <\/strong>O Nikkei Sports chamou o jogo de \u201cTrag\u00e9dia de Houston\u201d.<\/p>\n<p>O Sports Hochi, por sua vez, recordou os desfalques de peso da sele\u00e7\u00e3o nip\u00f4nica, desde antes da Copa, como Takumi Minamino e Kaoru Mitoma e Wataru Endo, como durante a competi\u00e7\u00e3o, caso do tamb\u00e9m meia Takefusa Kubo, que sofreu uma les\u00e3o no joelho esquerdo na fase de grupos. O artigo foi conclu\u00eddo reconhecendo que \u201co caminho para o t\u00edtulo mundial continua sendo \u00e1rduo\u201d para o Jap\u00e3o.<\/p>\n<p><strong>A sele\u00e7\u00e3o brasileira volta a campo no domingo (5), \u00e0s 17h (hor\u00e1rio de Bras\u00edlia), pelas oitavas de final.<\/strong> O duelo ser\u00e1 em Nova Jersey contra o ganhador do confronto entre Noruega e Costa do Marfim, que jogam nesta ter\u00e7a-feira (30), \u00e0s 14h, em Dallas, tamb\u00e9m nos Estados Unidos.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A vit\u00f3ria sobre o Jap\u00e3o, por 2 a 1, em Houston (Estados Unidos), que classificou&#8230;<\/p>\n","protected":false},"author":3,"featured_media":51816,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-55670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jogos-ao-vivo"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/seried.com.br\/wp-content\/uploads\/2025\/02\/Screenshot_20250203_230809_Chrome.jpg","_links":{"self":[{"href":"https:\/\/seried.com.br\/index.php\/wp-json\/wp\/v2\/posts\/55670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seried.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seried.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seried.com.br\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/seried.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=55670"}],"version-history":[{"count":0,"href":"https:\/\/seried.com.br\/index.php\/wp-json\/wp\/v2\/posts\/55670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seried.com.br\/index.php\/wp-json\/wp\/v2\/media\/51816"}],"wp:attachment":[{"href":"https:\/\/seried.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=55670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seried.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=55670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seried.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=55670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}